{"id":6366,"date":"2020-12-07T13:09:55","date_gmt":"2020-12-07T16:09:55","guid":{"rendered":"http:\/\/filo.unt.edu.ar\/noticias\/?p=6366"},"modified":"2020-12-21T12:02:04","modified_gmt":"2020-12-21T15:02:04","slug":"conferencia-sobre-el-ingreso-ciudadano","status":"publish","type":"post","link":"https:\/\/filo.unt.edu.ar\/noticias\/2020\/12\/07\/conferencia-sobre-el-ingreso-ciudadano\/","title":{"rendered":"Conferencia sobre el ingreso ciudadano."},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">El viernes 4 se llev\u00f3 a cabo la Conferencia &#8220;La propuesta del Ingreso Ciudadano. Reflexiones desde el Trabajo Social&#8221; que fue transmitida en vivo a trav\u00e9s del facebook del Colegio Trabajo Social Tucum\u00e1n.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">La actividad, destinada a estudiantes, profesionales y p\u00fablico en general, fue organizada en conjunto con la Carrera de Trabajo Social, la Secretar\u00eda de Extensi\u00f3n de la Facultad de Filosof\u00eda y Letras y el Colegio de Profesionales de Trabajo Social.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">La conferencia estuvo a cargo de Dra. Laura Garc\u00e9s, Trabajadora Social (UNSJ), Mg. en Ciencias Sociales con orientaci\u00f3n en Pol\u00edticas Sociales (UNC), Dra. en Ciencias Sociales (UBA), Directora Maestr\u00eda en Pol\u00edticas Sociales de UNSJ. Coautora del libro: El derecho a un Ingreso Ciudadano. Debates y experiencia en el Mundo y la Argentina.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Cabe destacar que la charla se realiz\u00f3 en el marco de las celebraciones por el D\u00eda del Trabajador\/a Social en Argentina, que en Tucum\u00e1n tiene la particularidad de coincidir este a\u00f1o con los 30 a\u00f1os de la creaci\u00f3n de la Carrera de Lic. en Trabajo Social en la Facultad de Filosof\u00eda y Letras de la UNT.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><a href=\"https:\/\/www.facebook.com\/colegiotrabajosocial.tucuman.92\/videos\/192083385862645\" target=\"_blank\" rel=\"noopener noreferrer\">VER CONFERENCIA.-<\/a><\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 4 se llev\u00f3 a cabo la Conferencia &#8220;La propuesta del Ingreso Ciudadano. Reflexiones desde el Trabajo Social&#8221; que fue transmitida en vivo a trav\u00e9s del facebook del Colegio Trabajo Social Tucum\u00e1n. La actividad, destinada a estudiantes, profesionales y p\u00fablico en general, fue organizada en conjunto con la Carrera [&hellip;]<\/p>\n","protected":false},"author":101021,"featured_media":6367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,6],"tags":[],"class_list":{"0":"post-6366","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-eventos-academicos","8":"category-extension","10":"post-with-thumbnail","11":"post-with-thumbnail-large"},"_links":{"self":[{"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/posts\/6366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/users\/101021"}],"replies":[{"embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/comments?post=6366"}],"version-history":[{"count":6,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/posts\/6366\/revisions"}],"predecessor-version":[{"id":6424,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/posts\/6366\/revisions\/6424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/media\/6367"}],"wp:attachment":[{"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/media?parent=6366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/categories?post=6366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/noticias\/wp-json\/wp\/v2\/tags?post=6366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}