{"id":16,"date":"2025-12-17T12:36:26","date_gmt":"2025-12-17T15:36:26","guid":{"rendered":"https:\/\/filo.unt.edu.ar\/aledar2026\/?page_id=16"},"modified":"2026-08-19T09:16:35","modified_gmt":"2026-08-19T12:16:35","slug":"trabajos","status":"publish","type":"page","link":"https:\/\/filo.unt.edu.ar\/aledar2026\/trabajos\/","title":{"rendered":"Trabajos"},"content":{"rendered":"<div id=\"pl-16\"  class=\"panel-layout\" ><div id=\"pg-16-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-16-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-16-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div style=\"font-family: Arial,Helvetica,sans-serif; text-align: left; overflow-wrap: break-word; padding: 40px 8px;\">\n<h2 style=\"font-family: Georgia,serif; font-size: 2em; line-height: 1.25; color: #124a63; margin: 0 0 24px; font-weight: normal;\">Criterios para el env\u00edo de trabajos<\/h2>\n<div style=\"background: #f5f9f7; border: 1px solid #dde8e0; border-radius: 8px; padding: 22px 24px; margin-bottom: 22px;\">\n<ul style=\"font-size: 0.95em; color: #333; line-height: 2; margin: 0; padding-left: 20px;\">\n<li>No m\u00e1s de 2 presentaciones por autor\/a<\/li>\n<li>Hasta 3 autores\/as por presentaci\u00f3n<\/li>\n<li>Entre 3 y 5 autores\/as por mesa coordinada<\/li>\n<li>Para recibir el certificado de exposici\u00f3n, todos\/as los\/as autores\/as deber\u00e1n pagar la inscripci\u00f3n al coloquio y la cuota societaria<\/li>\n<li>Autores\/as de trabajos no presentados no recibir\u00e1n certificado<\/li>\n<\/ul>\n<\/div>\n<div style=\"background: #eef3e9; border-left: 4px solid #6b9150; border-radius: 0 6px 6px 0; padding: 16px 20px;\">\n<div style=\"font-size: 0.95em; color: #3f5c2c; line-height: 1.7; word-break: break-word;\">Por consultas, escribir a <a style=\"color: #3f5c2c; font-weight: bold; text-decoration: none;\" href=\"mailto:aledar2026@filo.unt.edu.ar\">aledar2026@filo.unt.edu.ar<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Criterios para el env\u00edo de trabajos No m\u00e1s de 2 presentaciones por autor\/a Hasta 3 autores\/as por presentaci\u00f3n Entre 3 y 5 autores\/as por mesa coordinada Para recibir el certificado de exposici\u00f3n, todos\/as los\/as autores\/as deber\u00e1n pagar la inscripci\u00f3n al coloquio y la cuota societaria Autores\/as de trabajos no presentados no recibir\u00e1n certificado Por consultas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16","page","type-page","status-publish","hentry","post"],"_links":{"self":[{"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/pages\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":7,"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/pages\/16\/revisions"}],"predecessor-version":[{"id":111,"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/pages\/16\/revisions\/111"}],"wp:attachment":[{"href":"https:\/\/filo.unt.edu.ar\/aledar2026\/wp-json\/wp\/v2\/media?parent=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}